{"id":1,"count":66,"description":"HR\u2022Allgemein Beitrag","link":"https:\/\/www.pmp4you.support\/pmp\/category\/hr-allgemein-beitrag\/","name":"HR\u2022Allgemein","slug":"hr-allgemein-beitrag","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.pmp4you.support\/pmp\/wp-json\/wp\/v2\/categories\/1"}],"collection":[{"href":"https:\/\/www.pmp4you.support\/pmp\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.pmp4you.support\/pmp\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.pmp4you.support\/pmp\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}