{"id":15858,"date":"2020-01-01T00:00:19","date_gmt":"2019-12-31T23:00:19","guid":{"rendered":"https:\/\/www.pmp4you.support\/pmp\/?p=15858"},"modified":"2020-04-23T19:39:39","modified_gmt":"2020-04-23T17:39:39","slug":"seminarkalender-unsere-offenen-seminare","status":"publish","type":"post","link":"https:\/\/www.pmp4you.support\/pmp\/seminarkalender-unsere-offenen-seminare\/","title":{"rendered":"Seminarkalender &#8211; Unsere offenen Seminare"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Seminarkalender &#8211; Unsere offenen Seminare<\/h2>\n\n\n\n<p><span style=\"font-size: 14pt;\"><span style=\"color: #ff9900;\"><strong><span style=\"color: #ff9900;\">Erfolgreiche Beispiele<\/span><\/strong><\/span> unserer Arbeit als <strong><span style=\"color: #ff9900;\">Ideengeber<\/span><\/strong> &amp; <strong><span style=\"color: #ff9900;\">Denkansto\u00df<\/span><\/strong>:<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Seminarkalender &#8211; gehen Sie auf Entdeckungsreise<\/h3>\n\n\n\n<p>Werfen Sie doch einen Blick auf unseren Seminarkalender!<\/p>\n\n\n\n<p>Der Seminarkalender gibt f\u00fcr unsere offenen Seminare die n\u00f6tigen Hinweise auf:<\/p>\n\n\n\n<ul><li>die Seminarziele<\/li><li>die Seminarinhalte<\/li><li>die Seminartermine<\/li><li>den Seminarort<\/li><li>die Seminargeb\u00fchr<\/li><li>die Anmeldung<\/li><li>Link zur PDF-Seminarbeschreibung<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Werden Sie aktiv<\/h3>\n\n\n\n<p>Gerne erl\u00e4utern wir Ihnen in einem unverbindlichen Gespr\u00e4ch, mit welchen Leistungen wir Sie bei Ihren Herausforderungen unterst\u00fctzen k\u00f6nnen.<\/p>\n\n\n\n<p>Rufen Sie uns doch einfach an oder senden Sie uns ein E-Mail:<\/p>\n\n\n\n<p>+43 (0)662 441866, <a href=\"mailto:office@pmp.co.at\">office@pmp.co.at<\/a><\/p>\n\n\n\n<p>Sie wollen mehr dazu wissen \u2013 gehen Sie auf Entdeckungsreise:<\/p>\n\n\n\n<p><a href=\"\/pmp\/hr-development\/seminarkalender\/\">HR-Development \u2022 Seminarkalender<\/a><\/p>\n\n\n\n<p><a href=\"\/pmp\/ueber-pmp\/beispiele-unserer-arbeit\/\">Erfolgreiche Beispiele unserer Arbeit als Ideengeber und Denkanst\u00f6\u00dfe<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seminarkalender &#8211; Unsere offenen Seminare Erfolgreiche Beispiele unserer Arbeit als Ideengeber &amp; Denkansto\u00df: Seminarkalender &#8211; gehen Sie auf Entdeckungsreise Werfen Sie doch einen Blick auf unseren Seminarkalender! Der Seminarkalender gibt f\u00fcr unsere offenen Seminare die n\u00f6tigen Hinweise auf: die Seminarziele die Seminarinhalte die Seminartermine den Seminarort die Seminargeb\u00fchr die Anmeldung Link zur PDF-Seminarbeschreibung Werden Sie [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":11641,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[152],"tags":[131,123],"_links":{"self":[{"href":"https:\/\/www.pmp4you.support\/pmp\/wp-json\/wp\/v2\/posts\/15858"}],"collection":[{"href":"https:\/\/www.pmp4you.support\/pmp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmp4you.support\/pmp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmp4you.support\/pmp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmp4you.support\/pmp\/wp-json\/wp\/v2\/comments?post=15858"}],"version-history":[{"count":0,"href":"https:\/\/www.pmp4you.support\/pmp\/wp-json\/wp\/v2\/posts\/15858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmp4you.support\/pmp\/wp-json\/wp\/v2\/media\/11641"}],"wp:attachment":[{"href":"https:\/\/www.pmp4you.support\/pmp\/wp-json\/wp\/v2\/media?parent=15858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmp4you.support\/pmp\/wp-json\/wp\/v2\/categories?post=15858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmp4you.support\/pmp\/wp-json\/wp\/v2\/tags?post=15858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}